{"id":2973,"date":"2023-11-25T18:57:14","date_gmt":"2023-11-25T17:57:14","guid":{"rendered":"https:\/\/olotgironalloret.org\/associats\/educart\/"},"modified":"2023-11-25T19:03:00","modified_gmt":"2023-11-25T18:03:00","slug":"educart","status":"publish","type":"associats","link":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/","title":{"rendered":"educArt"},"content":{"rendered":"<p>EducArt, effectuer des visites guid\u00e9es destin\u00e9es \u00e0 faire conna\u00eetre les sites historiques de la r\u00e9gion de La Garrotxa. Il est compos\u00e9 d&rsquo;une \u00e9quipe d&rsquo;\u00e9ducateurs et de sp\u00e9cialistes pr\u00eats \u00e0 assister \u00e0 des groupes, des particuliers et des entreprises.<\/p>\n","protected":false},"featured_media":3279,"template":"","categoria-associat":[46],"zona":[42],"class_list":["post-2973","associats","type-associats","status-publish","has-post-thumbnail","hentry","categoria-associat-activites","zona-olot-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>educArt - OGL Meetings<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"educArt - OGL Meetings\" \/>\n<meta property=\"og:description\" content=\"EducArt, effectuer des visites guid\u00e9es destin\u00e9es \u00e0 faire conna\u00eetre les sites historiques de la r\u00e9gion de La Garrotxa. Il est compos\u00e9 d&rsquo;une \u00e9quipe d&rsquo;\u00e9ducateurs et de sp\u00e9cialistes pr\u00eats \u00e0 assister \u00e0 des groupes, des particuliers et des entreprises.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/\" \/>\n<meta property=\"og:site_name\" content=\"OGL Meetings\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-25T18:03:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/educart\\\/\",\"url\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/educart\\\/\",\"name\":\"educArt - OGL Meetings\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/educart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/educart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olotgironalloret.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/educArt1.jpeg\",\"datePublished\":\"2023-11-25T17:57:14+00:00\",\"dateModified\":\"2023-11-25T18:03:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/educart\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/educart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/educart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olotgironalloret.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/educArt1.jpeg\",\"contentUrl\":\"https:\\\/\\\/olotgironalloret.org\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/educArt1.jpeg\",\"width\":720,\"height\":405},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/educart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Associats\",\"item\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/associats\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"educArt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/\",\"name\":\"OGL Meetings\",\"description\":\"MICE \\\/ Reunions Projecte Olot Girona Lloret\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olotgironalloret.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"educArt - OGL Meetings","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/","og_locale":"fr_FR","og_type":"article","og_title":"educArt - OGL Meetings","og_description":"EducArt, effectuer des visites guid\u00e9es destin\u00e9es \u00e0 faire conna\u00eetre les sites historiques de la r\u00e9gion de La Garrotxa. Il est compos\u00e9 d&rsquo;une \u00e9quipe d&rsquo;\u00e9ducateurs et de sp\u00e9cialistes pr\u00eats \u00e0 assister \u00e0 des groupes, des particuliers et des entreprises.","og_url":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/","og_site_name":"OGL Meetings","article_modified_time":"2023-11-25T18:03:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/","url":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/","name":"educArt - OGL Meetings","isPartOf":{"@id":"https:\/\/olotgironalloret.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/#primaryimage"},"image":{"@id":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/#primaryimage"},"thumbnailUrl":"https:\/\/olotgironalloret.org\/wp-content\/uploads\/2023\/11\/educArt1.jpeg","datePublished":"2023-11-25T17:57:14+00:00","dateModified":"2023-11-25T18:03:00+00:00","breadcrumb":{"@id":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olotgironalloret.org\/fr\/associats\/educart\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/#primaryimage","url":"https:\/\/olotgironalloret.org\/wp-content\/uploads\/2023\/11\/educArt1.jpeg","contentUrl":"https:\/\/olotgironalloret.org\/wp-content\/uploads\/2023\/11\/educArt1.jpeg","width":720,"height":405},{"@type":"BreadcrumbList","@id":"https:\/\/olotgironalloret.org\/fr\/associats\/educart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/olotgironalloret.org\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Associats","item":"https:\/\/olotgironalloret.org\/fr\/associats\/"},{"@type":"ListItem","position":3,"name":"educArt"}]},{"@type":"WebSite","@id":"https:\/\/olotgironalloret.org\/fr\/#website","url":"https:\/\/olotgironalloret.org\/fr\/","name":"OGL Meetings","description":"MICE \/ Reunions Projecte Olot Girona Lloret","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olotgironalloret.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/olotgironalloret.org\/fr\/wp-json\/wp\/v2\/associats\/2973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olotgironalloret.org\/fr\/wp-json\/wp\/v2\/associats"}],"about":[{"href":"https:\/\/olotgironalloret.org\/fr\/wp-json\/wp\/v2\/types\/associats"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olotgironalloret.org\/fr\/wp-json\/wp\/v2\/media\/3279"}],"wp:attachment":[{"href":"https:\/\/olotgironalloret.org\/fr\/wp-json\/wp\/v2\/media?parent=2973"}],"wp:term":[{"taxonomy":"categoria-associat","embeddable":true,"href":"https:\/\/olotgironalloret.org\/fr\/wp-json\/wp\/v2\/categoria-associat?post=2973"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/olotgironalloret.org\/fr\/wp-json\/wp\/v2\/zona?post=2973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}